{"id":2542,"date":"2025-01-15T07:40:17","date_gmt":"2025-01-15T10:40:17","guid":{"rendered":"https:\/\/bmsolucoesedu.com.br\/portal\/?post_type=product&#038;p=2542"},"modified":"2025-11-04T10:20:28","modified_gmt":"2025-11-04T13:20:28","slug":"bola-de-futsal","status":"publish","type":"product","link":"https:\/\/bmsolucoesedu.com.br\/portal\/produtos\/bola-de-futsal\/","title":{"rendered":"Bola de futsal"},"content":{"rendered":"<p>Bola de futsal, confeccionada em laminado externo de PU 100%, com 11 gomos termossoldados, peso entre 410-430g e circunfer\u00eancia entre 62,5-63,5cm<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bola de futsal, confeccionada em laminado externo de PU 100%, com 11 gomos termossoldados, peso entre 410-430g e circunfer\u00eancia entre 62,5-63,5cm<\/p>\n","protected":false},"featured_media":2965,"template":"","meta":[],"product_brand":[],"product_cat":[638],"product_tag":[898],"class_list":{"0":"post-2542","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-material-esportivo","7":"product_tag-a126","8":"pa_item-279","9":"pa_lote-422","10":"pa_marca-penalty-max-1000","11":"pa_n-ata-19-2024","12":"pa_pregao-eletronico-por-registro-de-precos-no-019-2024","13":"pa_processo-licitatorio-019-2024","14":"wcpv_product_vendors-vale-comercio-de-produtos-para-educacao-ltda","16":"first","17":"instock","18":"shipping-taxable","19":"purchasable","20":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/bmsolucoesedu.com.br\/portal\/wp-json\/wp\/v2\/product\/2542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bmsolucoesedu.com.br\/portal\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bmsolucoesedu.com.br\/portal\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bmsolucoesedu.com.br\/portal\/wp-json\/wp\/v2\/media\/2965"}],"wp:attachment":[{"href":"https:\/\/bmsolucoesedu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=2542"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bmsolucoesedu.com.br\/portal\/wp-json\/wp\/v2\/product_brand?post=2542"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bmsolucoesedu.com.br\/portal\/wp-json\/wp\/v2\/product_cat?post=2542"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bmsolucoesedu.com.br\/portal\/wp-json\/wp\/v2\/product_tag?post=2542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}